{"id":10316,"date":"2018-02-19T13:01:08","date_gmt":"2018-02-19T10:01:08","guid":{"rendered":"http:\/\/ww-vb.mine.nu\/w108\/marseille-irresponsable-rellik-les-rendez-vous-series-du-19-au-25-fevrier\/"},"modified":"2018-02-19T13:01:08","modified_gmt":"2018-02-19T10:01:08","slug":"marseille-irresponsable-rellik-les-rendez-vous-series-du-19-au-25-fevrier","status":"publish","type":"post","link":"https:\/\/hameed.nwar.uk\/sa\/marseille-irresponsable-rellik-les-rendez-vous-series-du-19-au-25-fevrier\/","title":{"rendered":"Marseille, Irresponsable, Rellik&#8230; les rendez-vous s\u00e9ries du 19 au 25 f\u00e9vrier"},"content":{"rendered":"<p>Des nouveaux \u00e9pisodes de &quot;Marseille&quot; sur Netflix \u00e0 la saison 2 d&#039;&quot;Irresponsable&quot; sur OCS, tour d&#039;horizon des \u00e9v\u00e9nements s\u00e9ries de la semaine du 19 au 25 f\u00e9vrier.<\/p>\n<p>&gt;&gt; <a href=\"http:\/\/www.allocine.fr\/article\/fichearticle_gen_carticle=18670840.html\" rel=\"noreferrer\" target=\"_blank\">Lire l&#039;article<\/a>  | sur <a href=\"http:\/\/www.allocine.fr\/\" rel=\"noreferrer\" target=\"_blank\">AlloCin\u00e9<\/a>  &#8211; lundi 19 f\u00e9vrier 2018<\/p>\n<p><a href=http:\/\/www.allocine.fr\/article\/fichearticle_gen_carticle=18670840.html>Original Article<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des nouveaux \u00e9pisodes de &#8220;Marseille&#8221; sur Netflix \u00e0 la saison 2 d&#039;&#8221;Irresponsable&#8221; sur OCS, tour d&#039;horizon des \u00e9v\u00e9nements s\u00e9ries de la semaine du 19 au 25 f\u00e9vrier.>> Lire l&#039;article | sur AlloCin\u00e9 &#8211; lundi 19 f\u00e9vrier 2018<\/p>\n","protected":false},"author":1,"featured_media":10317,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-10316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tie-games"],"_links":{"self":[{"href":"https:\/\/hameed.nwar.uk\/sa\/wp-json\/wp\/v2\/posts\/10316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hameed.nwar.uk\/sa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hameed.nwar.uk\/sa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hameed.nwar.uk\/sa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hameed.nwar.uk\/sa\/wp-json\/wp\/v2\/comments?post=10316"}],"version-history":[{"count":0,"href":"https:\/\/hameed.nwar.uk\/sa\/wp-json\/wp\/v2\/posts\/10316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hameed.nwar.uk\/sa\/wp-json\/wp\/v2\/media\/10317"}],"wp:attachment":[{"href":"https:\/\/hameed.nwar.uk\/sa\/wp-json\/wp\/v2\/media?parent=10316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hameed.nwar.uk\/sa\/wp-json\/wp\/v2\/categories?post=10316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hameed.nwar.uk\/sa\/wp-json\/wp\/v2\/tags?post=10316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}